{"id":10713,"date":"2017-12-18T10:23:33","date_gmt":"2017-12-18T09:23:33","guid":{"rendered":"http:\/\/activite-piscine.com\/?p=10713"},"modified":"2017-12-18T18:25:45","modified_gmt":"2017-12-18T17:25:45","slug":"puissant-et-connecte","status":"publish","type":"post","link":"https:\/\/activite-piscine.com\/en\/news\/puissant-et-connecte\/","title":{"rendered":"Puissant et connect\u00e9"},"content":{"rendered":"<p>Le nouveau robot nettoyeur \u00e9lectrique Zodiac RV 5480 iQ est un concentr\u00e9 des innovations brevet\u00e9es Zodiac. Il dispose d\u2019une aspiration cyclonique surpuissante, d\u2019un vaste choix de programmes, de 4\u00a0roues motrices pour s\u2019adapter \u00e0 tous les rev\u00eatements et \u00eatre efficace partout dans le bassin\u00a0: marches, recoins, parois, ligne d\u2019eau et fond. Une fois le nettoyage termin\u00e9, sa fonction lift system permet de le r\u00e9cup\u00e9rer sans effort \u00e0 sa sortie de l\u2019eau. Le robot se place alors contre la paroi choisie et attend que l\u2019utilisateur le r\u00e9cup\u00e8re. Un puissant jet d\u2019eau permet alors de vider l\u2019eau accumul\u00e9e et d\u2019all\u00e9ger le poids du robot de 20\u00a0%. Mieux encore\u00a0: le robot RV 5480 iQ, lorsqu\u2019il est connect\u00e9 \u00e0 un r\u00e9seau wifi, est pilotable \u00e0 distance via un smartphone ou une tablette depuis n\u2019importe o\u00f9 gr\u00e2ce \u00e0 l\u2019application iAqualink\u2122. Le mode t\u00e9l\u00e9commande, int\u00e9gr\u00e9 \u00e0 l\u2019application, permet \u00e9galement de diriger le robot selon le besoin pour un nettoyage localis\u00e9 de pr\u00e9cision.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-10718\" src=\"http:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac.jpg\" alt=\"\" width=\"1200\" height=\"974\" srcset=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac.jpg 1200w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-300x244.jpg 300w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-768x623.jpg 768w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-1024x831.jpg 1024w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-600x487.jpg 600w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-1170x950.jpg 1170w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2017\/12\/zodiac-585x475.jpg 585w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.zodiac-poolcare.fr\" target=\"_blank\" rel=\"noopener\">www.zodiac-poolcare.fr<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le nouveau robot nettoyeur \u00e9lectrique Zodiac RV 5480 iQ est un concentr\u00e9 des innovations brevet\u00e9es Zodiac. Il dispose d\u2019une aspiration cyclonique surpuissante, d\u2019un vaste choix de programmes, de 4\u00a0roues motrices pour s\u2019adapter \u00e0 tous les rev\u00eatements et \u00eatre efficace partout dans le bassin\u00a0: marches, recoins, parois, ligne d\u2019eau et fond. Une fois le nettoyage termin\u00e9, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":10721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-10713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-produits"],"_links":{"self":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts\/10713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/comments?post=10713"}],"version-history":[{"count":0,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts\/10713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/media\/10721"}],"wp:attachment":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/media?parent=10713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/categories?post=10713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/tags?post=10713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}