{"id":53974,"date":"2026-05-13T17:51:08","date_gmt":"2026-05-13T15:51:08","guid":{"rendered":"https:\/\/activite-piscine.com\/?p=53974"},"modified":"2026-05-13T17:51:47","modified_gmt":"2026-05-13T15:51:47","slug":"diffaroc-bloc-technique-le-rocher-qui-cache-bien-son-jeu","status":"publish","type":"post","link":"https:\/\/activite-piscine.com\/en\/news\/diffaroc-bloc-technique-le-rocher-qui-cache-bien-son-jeu\/","title":{"rendered":"DIFFAROC Bloc technique : le rocher qui cache bien son jeu"},"content":{"rendered":"<p>Combien de fois un client a-t-il refus\u00e9 de voir sa filtration en \u00e9vidence au bord de la piscine ? La question, les piscinistes la connaissent par c\u0153ur. Diffaroc y r\u00e9pond depuis plus de 25 ans avec ses blocs techniques imitation rocher et en 2026, la gamme s\u2019enrichit d&rsquo;un nouveau mod\u00e8le interm\u00e9diaire au look revisit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-1024x683.jpg\" alt=\"\" class=\"wp-image-53976\" srcset=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-1024x683.jpg 1024w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-300x200.jpg 300w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-768x512.jpg 768w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-1536x1025.jpg 1536w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-2048x1366.jpg 2048w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Capots-ouverts-7-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Le principe : Une filtration invisible, un rocher qui l&rsquo;est vraiment<\/h2>\n\n\n\n<p>Le concept Diffaroc est simple et radical : un bac semi-enterr\u00e9 en polyester arm\u00e9 de fibres de verre accueille toute la filtration de la piscine, dissimul\u00e9 sous un capot reproduisant fid\u00e8lement la roche naturelle. R\u00e9sultat sur le terrain ? Z\u00e9ro local technique apparent, z\u00e9ro regard disgracieux. Le bloc s&rsquo;int\u00e8gre dans la v\u00e9g\u00e9tation comme s&rsquo;il avait toujours \u00e9t\u00e9 l\u00e0. <\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>100 % fabriqu\u00e9 en France, dans les ateliers Diffaroc \u00e0 Saint-Laurent-du-Var.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nouveau mod\u00e8le interm\u00e9diaire : format id\u00e9al et bon style<\/h2>\n\n\n\n<p>La nouveaut\u00e9 2026 ne se contente pas d&rsquo;occuper le cr\u00e9neau entre le petit et le grand mod\u00e8le : elle apporte une proposition de valeur distincte. Son capot adopte une silhouette plus basse et plus discr\u00e8te, tandis que son bac, lui, garde un volume utile g\u00e9n\u00e9reux pour loger les \u00e9quipements de filtration sans compromis. Cot\u00e9 teintes, il se d\u00e9cline en deux coloris, ocre et gris, pour s&rsquo;adapter et s\u2019int\u00e9grer \u00e0 tous les espaces. <\/p>\n\n\n\n<p>Ses dimensions : <strong>bac : 1.61 x 1.35 x h 0.62 m et capot : 1.69 x 1.41 x h 0.69 m<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;ouverture en un geste : accessibilit\u00e9 facilit\u00e9e<\/h2>\n\n\n\n<p>Le capot rocher s&rsquo;ouvre facilement et sans effort gr\u00e2ce aux v\u00e9rins int\u00e9gr\u00e9s. Fini les interventions compliqu\u00e9es lors des visites d&rsquo;entretien et de maintenance, un avantage que les piscinistes appr\u00e9cient autant que leurs clients. <\/p>\n\n\n\n<p>C\u00f4t\u00e9 pose, c&rsquo;est l&rsquo;un des points forts : la mise en \u0153uvre a \u00e9t\u00e9 pens\u00e9e pour aller vite et bien ! Le bac semi-enterr\u00e9 s\u2019installe sur une assise en gravier avec une \u00e9vacuation gravitaire, et le bloc est op\u00e9rationnel.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-entier-piscine-1-768x1024.png\" alt=\"\" class=\"wp-image-53979\" srcset=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-entier-piscine-1-768x1024.png 768w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-entier-piscine-1-225x300.png 225w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-entier-piscine-1-9x12.png 9w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-entier-piscine-1.png 896w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-Zoom.jpg\" alt=\"\" class=\"wp-image-53978\" srcset=\"https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-Zoom.jpg 768w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-Zoom-225x300.jpg 225w, https:\/\/activite-piscine.com\/wp-content\/uploads\/2026\/05\/Rocher-Zoom-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Combien de fois un client a-t-il refus\u00e9 de voir sa filtration en \u00e9vidence au bord de la piscine ? La question, les piscinistes la connaissent par c\u0153ur. Diffaroc y r\u00e9pond depuis plus de 25 ans avec ses blocs techniques imitation rocher et en 2026, la gamme s\u2019enrichit d&rsquo;un nouveau mod\u00e8le interm\u00e9diaire au look revisit\u00e9. Le [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":53975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-53974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-produits"],"_links":{"self":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts\/53974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/comments?post=53974"}],"version-history":[{"count":2,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts\/53974\/revisions"}],"predecessor-version":[{"id":53981,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/posts\/53974\/revisions\/53981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/media\/53975"}],"wp:attachment":[{"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/media?parent=53974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/categories?post=53974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/activite-piscine.com\/en\/wp-json\/wp\/v2\/tags?post=53974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}